{"id":1396,"date":"2025-05-14T10:36:28","date_gmt":"2025-05-14T07:36:28","guid":{"rendered":"https:\/\/drozdemirclinic.com\/?page_id=1396"},"modified":"2025-05-15T13:14:42","modified_gmt":"2025-05-15T10:14:42","slug":"dhi-haartransplantation","status":"publish","type":"page","link":"https:\/\/drozdemirclinic.com\/de\/haar\/dhi-haartransplantation\/","title":{"rendered":"DHI Haartransplantation"},"content":{"rendered":"\n<!-- Mobil men\u00fc butonu -->\n<div class=\"thi-mobile-menu-btn\">\n    <i class=\"fas fa-bars\"><\/i>\n<\/div>\n\n<!-- Mobil men\u00fc -->\n<div class=\"thi-mobile-menu\">\n    <!-- Men\u00fc kapatma butonu -->\n    <div class=\"thi-mobile-menu-close\">\n        <i class=\"fas fa-times\"><\/i>\n    <\/div>\n    \n    <!-- Mobil men\u00fc logosu -->\n    <div class=\"thi-mobile-menu-logo\">\n        <img decoding=\"async\" src=\"https:\/\/drozdemirclinic.com\/wp-content\/uploads\/2025\/04\/drozdemirlogo666-scaled.png\" alt=\"Dr Ozdemir Clinic Logo\">\n    <\/div>\n    \n    <ul class=\"thi-mobile-menu-items\">\n        <li class=\"thi-mobile-menu-item\">\n            <a href=\"https:\/\/drozdemirclinic.com\/de\/haar\" class=\"thi-mobile-menu-link\">\n                <span class=\"thi-expand-icon\">&#8211;<\/span>HAAR\n            <\/a>\n        <\/li>\n        <li class=\"thi-mobile-menu-item\">\n            <a href=\"https:\/\/drozdemirclinic.com\/de\/zahn\" class=\"thi-mobile-menu-link\">\n                <span class=\"thi-expand-icon\">\u2212<\/span>ZAHN\n            <\/a>\n        <\/li>\n        <li class=\"thi-mobile-menu-item\">\n            <a href=\"https:\/\/drozdemirclinic.com\/de\/plastisch\" class=\"thi-mobile-menu-link\">\n                <span class=\"thi-expand-icon\">\u2212<\/span>PLASTISCH\n            <\/a>\n        <\/li>\n        <li class=\"thi-mobile-menu-item\">\n            <a href=\"https:\/\/drozdemirclinic.com\/de\/medizinisch\" class=\"thi-mobile-menu-link\">\n                <span class=\"thi-expand-icon\">\u2212<\/span>MEDIZINISCH\n            <\/a>\n        <\/li>\n        <li class=\"thi-mobile-menu-item\">\n            <a href=\"https:\/\/drozdemirclinic.com\/de\/therapien\" class=\"thi-mobile-menu-link\">\n                <span class=\"thi-expand-icon\">\u2212<\/span>THERAPIEN\n            <\/a>\n        <\/li>\n    <\/ul>\n<\/div>\n\n<!-- Hauptinhalt -->\n<main class=\"thi-main-content\">\n    <!-- Header-Komponente -->\n    <div class=\"thi-headerImage\">\n        <div class=\"thi-desktop-logo\">\n            <a href=\"https:\/\/drozdemirclinic.com\/de\/\">\n                <!-- Desktop-Logo (Standard) -->\n                <img decoding=\"async\" src=\"https:\/\/drozdemirclinic.com\/wp-content\/uploads\/2025\/04\/logo34.png\" class=\"desktop-only-logo img-fluid\" alt=\"Dr Ozdemir Clinic Logo\">\n                <!-- Mobiles Logo (f\u00fcr mobile Ansicht) -->\n                <img decoding=\"async\" src=\"https:\/\/drozdemirclinic.com\/wp-content\/uploads\/2025\/04\/drozdemirlogo22-scaled.png\" class=\"mobile-only-logo img-fluid\" alt=\"Dr Ozdemir Clinic Logo\">\n            <\/a>\n        <\/div>\n        <img decoding=\"async\" src=\"https:\/\/drozdemirclinic.com\/wp-content\/uploads\/2025\/04\/dv_optimized.webp\" alt=\"Medizinische Einrichtung Innenansicht\">\n        \n        <!-- Hero-Bild in der Mitte und unten -->\n        <div class=\"thi-hero-bottom-image\">\n            <!-- Text-Overlays - f\u00fcr jeden Slide -->\n            <div class=\"thi-hero-text-overlay active\" data-slide=\"0\">\n                <h1 style=\"color: black;\">DHI<\/h1>\n            <\/div>\n            \n            <!-- Slider-Bilder -->\n            <div class=\"thi-slider-container\">\n                <img decoding=\"async\" src=\"https:\/\/drozdemirclinic.com\/wp-content\/uploads\/2025\/04\/efe2.png\" alt=\"Haartransplantation Bild\" class=\"thi-slider-image active\">\n            <\/div>\n        <\/div>\n    <\/div>\n    \n    <!-- Navbar-Komponente (f\u00fcr Desktop) -->\n    <nav class=\"thi-navbar\">\n        <div class=\"thi-nav-container\">\n            <ul class=\"thi-nav-menu\">\n                <li class=\"thi-nav-item\">\n                    <a href=\"https:\/\/drozdemirclinic.com\/de\/haar\" class=\"thi-nav-link\">HAAR<\/a>\n                <\/li>\n                <li class=\"thi-nav-item\">\n                    <a href=\"https:\/\/drozdemirclinic.com\/de\/zahn\" class=\"thi-nav-link\">ZAHN<\/a>\n                <\/li>\n                <li class=\"thi-nav-item\">\n                    <a href=\"https:\/\/drozdemirclinic.com\/de\/plastisch\" class=\"thi-nav-link\">PLASTISCH<\/a>\n                <\/li>\n                <li class=\"thi-nav-item\">\n                    <a href=\"https:\/\/drozdemirclinic.com\/de\/medizinisch\" class=\"thi-nav-link\">MEDIZINISCH<\/a>\n                <\/li>\n                <li class=\"thi-nav-item\">\n                    <a href=\"https:\/\/drozdemirclinic.com\/de\/therapien\" class=\"thi-nav-link\">THERAPIEN<\/a>\n                <\/li>\n            <\/ul>\n        <\/div>\n    <\/nav>\n\n    <!-- Inhaltsbereich -->\n    <section class=\"thi-sapphire-section\">\n        <div class=\"thi-sapphire-content-wrapper\">\n            <div class=\"thi-sapphire-left-content\">\n                <h1 class=\"thi-sapphire-title\">DHI Haartransplantation<\/h1>\n                <div class=\"thi-sapphire-text\">\n                    <p>\n                        Die DHI (Direct Hair Implantation) Haartransplantation ist eine fortschrittliche Methode, die mit speziellen Choi-Stiften durchgef\u00fchrt wird. Bei dieser Technik werden die Haarwurzeln direkt in die Kopfhaut implantiert. Da keine Kanal\u00f6ffnung erforderlich ist, ist der Eingriff weniger traumatisch und die Heilung verl\u00e4uft schneller.\n\n                        Die DHI-Technik erm\u00f6glicht eine pr\u00e4zisere und kontrollierte Platzierung der Haarwurzeln. Dadurch k\u00f6nnen die Austrittswinkel und -richtungen der Haare entsprechend der nat\u00fcrlichen Haarlinie angepasst werden. Au\u00dferdem ist die \u00dcberlebensrate der Transplantate h\u00f6her, da die Haarwurzeln k\u00fcrzer der Umgebung ausgesetzt sind.\n\n                        F\u00fcr jeden Patienten wird eine individuelle Planung erstellt und die Transplantation unter Ber\u00fccksichtigung der nat\u00fcrlichen Haarlinie durchgef\u00fchrt. Der Eingriff erfolgt unter \u00f6rtlicher Bet\u00e4ubung und wird in einer Sitzung abgeschlossen. Die Ergebnisse sind nach 12-15 Monaten vollst\u00e4ndig sichtbar und lebenslang haltbar.\n                    <\/p>\n                <\/div>\n                <div class=\"thi-sapphire-warning\">\n                    <span class=\"thi-sapphire-warning-icon\">\n                        <i class=\"fas fa-exclamation-triangle\"><\/i>\n                    <\/span>\n                    <span>Jeder Mensch ist anders. Der Operationsprozess und die Verfahren k\u00f6nnen je nach Ihrer individuellen Situation variieren.<\/span>\n                <\/div>\n            <\/div>\n            <div class=\"thi-sapphire-right-image\">\n                <img decoding=\"async\" src=\"https:\/\/drozdemirclinic.com\/wp-content\/uploads\/2025\/04\/efe2.png\" alt=\"DHI Haartransplantation\">\n            <\/div>\n        <\/div>\n    <\/section>\n\n    <!-- Tab-Buttons -->\n    <div class=\"thi-tabs-container\">\n        <div class=\"thi-tab-buttons\">\n            <button class=\"thi-tab-button active\">\u00dcber uns<\/button>\n            <button class=\"thi-tab-button\">Vorher \/ Nachher<\/button>\n        <\/div>\n    <\/div>\n\n    <!-- \u00dcber uns Bereich -->\n    <section id=\"about\" class=\"thi-about-section\">\n        <div class=\"thi-about-container\">\n            <article class=\"thi-about-content\">\n                <h2>Was ist DHI Haartransplantation?<\/h2>\n                <p>Die DHI (Direct Hair Implantation) Haartransplantation ist eine moderne Behandlungsmethode f\u00fcr nat\u00fcrliche und dauerhafte Haare. Bei diesem Verfahren werden die Haarwurzeln mit speziellen Choi-Stiften direkt in die Kopfhaut implantiert. Da keine Kanal\u00f6ffnung erforderlich ist, wird maximale Nat\u00fcrlichkeit bei minimalem Trauma erreicht.<\/p>\n\n                <h3>Geeignete Kandidaten f\u00fcr DHI<\/h3>\n                <p>Die DHI-Haartransplantation ist ideal f\u00fcr Menschen mit Haarausfall, die nat\u00fcrlich aussehende Ergebnisse w\u00fcnschen. Besonders geeignet ist sie f\u00fcr Menschen mit feinem Haar und Frauen. Auch f\u00fcr Bereiche, die eine dichte Haartransplantation erfordern, ist sie geeignet. Allerdings sollten Personen mit aktiven Kopfhautinfektionen oder schwerwiegenden Gesundheitsproblemen diese zun\u00e4chst behandeln lassen.<\/p>\n\n                <h3>Wie wird DHI durchgef\u00fchrt?<\/h3>\n                <p>Die DHI-Technik wird mit der direkten Implantationsmethode unter Verwendung spezieller Choi-Stifte durchgef\u00fchrt. Zun\u00e4chst werden die aus dem Spenderbereich entnommenen Haarwurzeln in einer speziellen L\u00f6sung aufbewahrt. Anschlie\u00dfend wird jede Haarwurzel einzeln mit dem Choi-Stift implantiert. Durch diesen pr\u00e4zisen Vorgang k\u00f6nnen die Austrittswinkel und -richtungen der Haare vollst\u00e4ndig kontrolliert werden.<\/p>\n\n                <h3>Vorteile von DHI<\/h3>\n                <p>Die DHI-Technik bietet viele Vorteile: Keine Kanal\u00f6ffnung erforderlich, weniger traumatisch, k\u00fcrzere Heilungszeit, h\u00f6here \u00dcberlebensrate der Transplantate und M\u00f6glichkeit einer dichteren Transplantation. Au\u00dferdem werden sehr nat\u00fcrliche Ergebnisse erzielt, da die Austrittswinkel und -richtungen der Haare vollst\u00e4ndig kontrolliert werden k\u00f6nnen.<\/p>\n\n                <h3>DHI-Phasen<\/h3>\n                <ul class=\"thi-treatment-steps\">\n                    <li><strong>Planung und Vorbereitung:<\/strong> Vor der Haartransplantation wird eine detaillierte Analyse durchgef\u00fchrt, die Haarlinie bestimmt und ein Transplantationsplan erstellt.<\/li>\n                    <li><strong>Transplantatentnahme:<\/strong> Die Haarwurzeln werden mit einem speziellen Mikromotor aus dem Spenderbereich entnommen und in einer speziellen L\u00f6sung aufbewahrt.<\/li>\n                    <li><strong>DHI-Anwendung:<\/strong> Die Haarwurzeln werden mit Choi-Stiften direkt in die Kopfhaut implantiert.<\/li>\n                <\/ul>\n\n                <h3>Nachsorge nach DHI<\/h3>\n                <p>In der ersten Woche nach DHI ist eine spezielle Pflege erforderlich. Es ist wichtig, die Empfehlungen des Arztes bez\u00fcglich Haarw\u00e4sche, Schlafposition und k\u00f6rperlicher Aktivit\u00e4t zu befolgen. Die erste Haarw\u00e4sche erfolgt nach 2-3 Tagen. Im ersten Monat sollte man vorsichtig sein und direktes Sonnenlicht vermeiden.<\/p>\n\n                <h3>Ist DHI schmerzhaft?<\/h3>\n                <p>Die DHI-Behandlung wird unter \u00f6rtlicher Bet\u00e4ubung durchgef\u00fchrt und ist w\u00e4hrend des Eingriffs schmerzfrei. Nach dem Eingriff kann eine leichte Spannung auftreten, die jedoch vor\u00fcbergehend ist und mit Schmerzmitteln kontrolliert werden kann.<\/p>\n\n                <h3>DHI-Preise 2025<\/h3>\n                <p>Die Preise f\u00fcr DHI-Haartransplantationen variieren je nach Anzahl der zu transplantierenden Grafts, Umfang des Eingriffs und Qualit\u00e4t der Klinikleistungen. F\u00fcr detaillierte Informationen und ein personalisiertes Preisangebot k\u00f6nnen Sie sich an unsere Klinik wenden.<\/p>\n            <\/article>\n        <\/div>\n    <\/section>\n\n    <!-- Vorher\/Nachher Bereich -->\n    <section id=\"before-after\" class=\"thi-before-after-section\">\n        <div class=\"thi-before-after-grid\">\n            <!-- DHI Vorher\/Nachher Beispiele -->\n            <div class=\"thi-before-after-item\">\n                <h3>DHI Haartransplantation<\/h3>\n                <div class=\"thi-before-after-images\">\n                    <div class=\"thi-before\">\n                        <img decoding=\"async\" src=\"https:\/\/images.unsplash.com\/photo-1590540179852-219674b2a8a6\" alt=\"DHI Vorher\">\n                        <span class=\"thi-label\">Vorher<\/span>\n                    <\/div>\n                    <div class=\"thi-after\">\n                        <img decoding=\"async\" src=\"https:\/\/images.unsplash.com\/photo-1633332755192-727a05c4013d\" alt=\"DHI Nachher\">\n                        <span class=\"thi-label\">Nachher<\/span>\n                    <\/div>\n                <\/div>\n            <\/div>\n\n            <!-- DHI Vorher\/Nachher 2 -->\n            <div class=\"thi-before-after-item\">\n                <h3>DHI Haartransplantation<\/h3>\n                <div class=\"thi-before-after-images\">\n                    <div class=\"thi-before\">\n                        <img decoding=\"async\" src=\"https:\/\/images.unsplash.com\/photo-1595152772835-219674b2a8a6\" alt=\"DHI Vorher\">\n                        <span class=\"thi-label\">Vorher<\/span>\n                    <\/div>\n                    <div class=\"thi-after\">\n                        <img decoding=\"async\" src=\"https:\/\/images.unsplash.com\/photo-1570295999919-56ceb5ecca61\" alt=\"DHI Nachher\">\n                        <span class=\"thi-label\">Nachher<\/span>\n                    <\/div>\n                <\/div>\n            <\/div>\n\n            <!-- DHI Vorher\/Nachher 3 -->\n            <div class=\"thi-before-after-item\">\n                <h3>DHI Haartransplantation<\/h3>\n                <div class=\"thi-before-after-images\">\n                    <div class=\"thi-before\">\n                        <img decoding=\"async\" src=\"https:\/\/images.unsplash.com\/photo-1580489944761-15a19d654956\" alt=\"DHI Vorher\">\n                        <span class=\"thi-label\">Vorher<\/span>\n                    <\/div>\n                    <div class=\"thi-after\">\n                        <img decoding=\"async\" src=\"https:\/\/images.unsplash.com\/photo-1531746020798-e6953c6e8e04\" alt=\"DHI Nachher\">\n                        <span class=\"thi-label\">Nachher<\/span>\n                    <\/div>\n                <\/div>\n            <\/div>\n\n            <!-- DHI Vorher\/Nachher 4 -->\n            <div class=\"thi-before-after-item\">\n                <h3>DHI Haartransplantation<\/h3>\n                <div class=\"thi-before-after-images\">\n                    <div class=\"thi-before\">\n                        <img decoding=\"async\" src=\"https:\/\/images.unsplash.com\/photo-1585747860715-2ba37e788b70\" alt=\"DHI Vorher\">\n                        <span class=\"thi-label\">Vorher<\/span>\n                    <\/div>\n                    <div class=\"thi-after\">\n                        <img decoding=\"async\" src=\"https:\/\/images.unsplash.com\/photo-1622363294459-22944b8c1df7\" alt=\"DHI Nachher\">\n                        <span class=\"thi-label\">Nachher<\/span>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n<\/main>\n\n\n\n<!-- Kons\u00fcltasyon Butonlar\u0131 -->\n<div class=\"thi-consultation-buttons\">\n    <a href=\"#\" class=\"thi-consultation-btn thi-meet-btn\">\n        <div class=\"btn-icon\">\n            <img decoding=\"async\" src=\"https:\/\/drozdemirclinic.com\/wp-content\/uploads\/2025\/04\/google.png\" alt=\"Google Meet\" class=\"meet-icon\">\n        <\/div>\n        <div class=\"btn-text\">\n            <span class=\"btn-title\">Kostenlose Beratung<\/span>\n            <span class=\"btn-subtitle\">Online Termin vereinbaren<\/span>\n        <\/div>\n    <\/a>\n    <a href=\"#\" class=\"thi-consultation-btn thi-whatsapp-btn\">\n        <div class=\"btn-icon\">\n            <i class=\"fab fa-whatsapp\"><\/i>\n        <\/div>\n        <div class=\"btn-text\">\n            <span class=\"btn-title\">24\/7 Support<\/span>\n            <span class=\"btn-subtitle\">Schreiben Sie uns auf WhatsApp<\/span>\n        <\/div>\n    <\/a>\n<\/div>\n<\/main>\n\n\n\n<footer class=\"doc-footer\">\n    <div class=\"doc-footer-container\">\n\n<a href=\"https:\/\/drozdemirclinic.com\/de\/\">\n<img decoding=\"async\" src=\"https:\/\/drozdemirclinic.com\/wp-content\/uploads\/2025\/04\/drozdemirlogo666-scaled.png\" alt=\"Dr. \u00d6zdemir Turkish Hair Institute\" class=\"doc-footer-logo\">\n<\/a>\n\n     <div class=\"doc-social-links\">\n                <a href=\"https:\/\/www.facebook.com\/ozdemirclinic\" class=\"doc-social-link\" aria-label=\"Facebook\" target=\"_blank\" rel=\"noopener\"><i class=\"fab fa-facebook-f\"><\/i><\/a>\n                <a href=\"https:\/\/www.instagram.com\/drozdemirclinic\" class=\"doc-social-link\" aria-label=\"Instagram\" target=\"_blank\" rel=\"noopener\"><i class=\"fab fa-instagram\"><\/i><\/a>\n                <a href=\"https:\/\/www.linkedin.com\/company\/drozdemirclinic\" class=\"doc-social-link\" aria-label=\"Twitter\" target=\"_blank\" rel=\"noopener\"><i class=\"fab fa-linkedin-in\"><\/i><\/a>\n                <a href=\"https:\/\/www.youtube.com\/@drozdemirclinic\" class=\"doc-social-link\" aria-label=\"Youtube\" target=\"_blank\" rel=\"noopener\"><i class=\"fab fa-youtube\"><\/i><\/a>\n                <a href=\"#\" class=\"doc-social-link\" aria-label=\"WhatsApp\"><i class=\"fab fa-whatsapp\"><\/i><\/a>\n            <\/div>\n        \n        <div class=\"doc-footer-main\">\n            <div class=\"doc-footer-section\">\n                <h3 class=\"doc-footer-heading\">Ihr Experte f\u00fcr Haartransplantation und Behandlung<\/h3>\n                <p>Mit unseren innovativen Behandlungsmethoden, unserem Expertenteam und moderner Technologie bieten wir dauerhafte L\u00f6sungen f\u00fcr Ihre Haargesundheit.<\/p>\n            <\/div>\n            \n            <div class=\"doc-footer-section\">\n                <h3 class=\"doc-footer-heading\">Unsere Behandlungen<\/h3>\n                <div class=\"doc-footer-links\">\n                    <a href=\"https:\/\/drozdemirclinic.com\/de\/haar\" class=\"doc-footer-link\"><i class=\"fas fa-chevron-right\"><\/i> Haar<\/a>\n                    <a href=\"https:\/\/drozdemirclinic.com\/de\/zahn\" class=\"doc-footer-link\"><i class=\"fas fa-chevron-right\"><\/i> Zahn<\/a>\n                    <a href=\"https:\/\/drozdemirclinic.com\/de\/plastische-chirurgie\" class=\"doc-footer-link\"><i class=\"fas fa-chevron-right\"><\/i> Plastische Chirurgie<\/a>\n                    <a href=\"https:\/\/drozdemirclinic.com\/de\/medizinisch\" class=\"doc-footer-link\"><i class=\"fas fa-chevron-right\"><\/i> Medizinisch<\/a>\n                    <a href=\"https:\/\/drozdemirclinic.com\/de\/therapien\" class=\"doc-footer-link\"><i class=\"fas fa-chevron-right\"><\/i> Therapien<\/a>\n                <\/div>\n            <\/div>\n            \n            <div class=\"doc-footer-section\">\n                <h3 class=\"doc-footer-heading\">Unternehmen<\/h3>\n                <div class=\"doc-footer-links\">\n                    <a href=\"https:\/\/drozdemirclinic.com\/de\/uber-uns\" class=\"doc-footer-link\"><i class=\"fas fa-chevron-right\"><\/i> \u00dcber uns<\/a>\n                    <a href=\"https:\/\/drozdemirclinic.com\/de\/kontakt\" class=\"doc-footer-link\"><i class=\"fas fa-chevron-right\"><\/i> Kontakt<\/a>\n                    <a href=\"https:\/\/drozdemirclinic.com\/de\/blog\" class=\"doc-footer-link\"><i class=\"fas fa-chevron-right\"><\/i> Blog<\/a>\n                    <a href=\"https:\/\/drozdemirclinic.com\/de\/wissensdatenbank\" class=\"doc-footer-link\"><i class=\"fas fa-chevron-right\"><\/i> Wissensdatenbank<\/a>\n                    <a href=\"https:\/\/drozdemirclinic.com\/de\/faq\" class=\"doc-footer-link\"><i class=\"fas fa-chevron-right\"><\/i> FAQ<\/a>\n                <\/div>\n            <\/div>\n\n            <div class=\"doc-footer-section\">\n                <h3 class=\"doc-footer-heading\">Vertr\u00e4ge &#038; Richtlinien<\/h3>\n                <div class=\"doc-footer-links\">\n                    <a href=\"https:\/\/drozdemirclinic.com\/de\/bedingungen-und-konditionen\/#kvkk\" class=\"doc-footer-link\"><i class=\"fas fa-chevron-right\"><\/i> Datenschutzerkl\u00e4rung<\/a>\n                    <a href=\"https:\/\/drozdemirclinic.com\/de\/bedingungen-und-konditionen\/#privacy\" class=\"doc-footer-link\"><i class=\"fas fa-chevron-right\"><\/i> Datenschutzrichtlinie<\/a>\n                    <a href=\"https:\/\/drozdemirclinic.com\/de\/bedingungen-und-konditionen\/#cookie\" class=\"doc-footer-link\"><i class=\"fas fa-chevron-right\"><\/i> Cookie-Richtlinie<\/a>\n                    <a href=\"https:\/\/drozdemirclinic.com\/de\/bedingungen-und-konditionen\/#dsgvo\" class=\"doc-footer-link\"><i class=\"fas fa-chevron-right\"><\/i> DSGVO<\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n    \n    <div class=\"doc-footer-bottom\">\n        <div class=\"doc-copyright\">\u00a92025 DROZDEM\u0130R CL\u0130N\u0130C Alle Rechte vorbehalten.<\/div>\n    <\/div>\n<\/footer>\n\n\n<p>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1469-o1\" lang=\"tr-TR\" dir=\"ltr\" data-wpcf7-id=\"1469\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/de\/wp-json\/wp\/v2\/pages\/1396#wpcf7-f1469-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1469\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.3\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"tr_TR\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1469-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<!-- \u0130leti\u015fim Formu -->\n<div class=\"thi-form-container\">\n\t<h3 class=\"thi-form-title\">Kostenlose Beratung\n\t<\/h3>\n\t<div class=\"thi-form\">\n\t\t<div class=\"thi-form-group\">\n\t\t\t<p><i class=\"fas fa-user thi-form-icon\"><\/i><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required thi-form-input\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Vor- und Nachname\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"thi-form-group\">\n\t\t\t<p><i class=\"fas fa-envelope thi-form-icon\"><\/i><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email thi-form-input\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-Mail-Adresse\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"thi-form-group\">\n\t\t\t<p><i class=\"fas fa-phone thi-form-icon\"><\/i><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel thi-form-input\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Telefonnummer\" value=\"\" type=\"tel\" name=\"your-tel\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"thi-form-checkbox-group\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"kvkk\"><span class=\"wpcf7-form-control wpcf7-checkbox wpcf7-validates-as-required thi-form-checkbox\" id=\"kvkk-checkbox\"><span class=\"wpcf7-list-item first last\"><label><input type=\"checkbox\" name=\"kvkk[]\" value=\"Ich stimme der Verarbeitung meiner personenbezogenen Daten f\u00fcr Gesundheitsdienstleistungen gem\u00e4\u00df dem Datenschutzgesetz zu.\" \/><span class=\"wpcf7-list-item-label\">Ich stimme der Verarbeitung meiner personenbezogenen Daten f\u00fcr Gesundheitsdienstleistungen gem\u00e4\u00df dem Datenschutzgesetz zu.<\/span><\/label><\/span><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"thi-form-button-group\">\n\t\t\t<div class=\"submit-button-wrapper\">\n\t\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner thi-form-button thi-form-submit\" type=\"submit\" value=\"Senden\" \/><br \/>\n<i class=\"fas fa-paper-plane submit-icon\"><\/i>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<p><a href=\"https:\/\/wa.me\/905000000000\" class=\"thi-form-button thi-form-whatsapp\" target=\"_blank\" rel=\"noopener\"><br \/>\n<i class=\"fab fa-whatsapp\"><\/i> WhatsApp<br \/>\n<\/a>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n <!-- Cookie Banner -->\n<div class=\"cookie-banner\" id=\"cookieBanner_3\">\n    <div class=\"cookie-content\">\n        <div class=\"cookie-icon\">\n            <i class=\"fas fa-cookie-bite\"><\/i>\n        <\/div>\n        <div class=\"cookie-text\">\n            <h3>Cookie-Benachrichtigung<\/h3>\n            <p><p>Diese Website verwendet Cookies, um Ihr Erlebnis zu verbessern. Durch die weitere Nutzung unserer Website erkl\u00e4ren Sie sich mit unseren Datenschutzbestimmungen und Nutzungsbedingungen einverstanden.<\/p><\/p>\n        <\/div>\n        <div class=\"cookie-buttons\">\n            <button id=\"acceptCookies_3\" class=\"cookie-btn accept\">\n                <i class=\"fas fa-check\"><\/i> Akzeptieren            <\/button>\n            <button id=\"cookiePreferences_3\" class=\"cookie-btn preferences\">\n                <i class=\"fas fa-cog\"><\/i> Pr\u00e4ferenzen            <\/button>\n        <\/div>\n    <\/div>\n<\/div>\n\n<!-- Cookie Tercihler Paneli -->\n<div class=\"preferences-panel\" id=\"preferencesPanel_3\">\n    <div class=\"preferences-content\">\n        <div class=\"preferences-header\">\n            <h3>Cookie-Einstellungen<\/h3>\n            <button id=\"closePreferences_3\" class=\"close-btn\">\n                <i class=\"fas fa-times\"><\/i>\n            <\/button>\n        <\/div>\n        <div class=\"preferences-options\">\n            <div class=\"preference-item\">\n                <label class=\"switch\">\n                    <input type=\"checkbox\" checked disabled>\n                    <span class=\"slider\"><\/span>\n                <\/label>\n                <div class=\"preference-text\">\n                    <h4>Erforderliche Cookies<\/h4>\n                    <p><p>Diese Cookies sind f\u00fcr das Funktionieren der Website unerl\u00e4sslich und k\u00f6nnen nicht deaktiviert werden.<\/p><\/p>\n                <\/div>\n            <\/div>\n            <div class=\"preference-item\">\n                <label class=\"switch\">\n                    <input type=\"checkbox\" id=\"analyticsCheck_3\">\n                    <span class=\"slider\"><\/span>\n                <\/label>\n                <div class=\"preference-text\">\n                    <h4>Analytische Cookies<\/h4>\n                    <p><p>Analytische Cookies helfen uns, den Website-Verkehr zu analysieren und die Benutzerfreundlichkeit zu verbessern.<\/p><\/p>\n                <\/div>\n            <\/div>\n            <div class=\"preference-item\">\n                <label class=\"switch\">\n                    <input type=\"checkbox\" id=\"marketingCheck_3\">\n                    <span class=\"slider\"><\/span>\n                <\/label>\n                <div class=\"preference-text\">\n                    <h4>Marketing-Cookies<\/h4>\n                    <p><p>Es hilft uns, Ihnen auf Ihre Interessen zugeschnittene Werbung zu pr\u00e4sentieren.<\/p><\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div class=\"preferences-buttons\">\n            <button id=\"savePreferences_3\" class=\"cookie-btn accept\">\n                <i class=\"fas fa-save\"><\/i> Speichern Sie            <\/button>\n        <\/div>\n    <\/div>\n<\/div>\n\n<script type=\"text\/javascript\">\njQuery(document).ready(function($) {\n    \/\/ DOM Elementleri\n    const cookieBanner = document.getElementById('cookieBanner_3');\n    const preferencesPanel = document.getElementById('preferencesPanel_3');\n    const acceptCookiesBtn = document.getElementById('acceptCookies_3');\n    const cookiePreferencesBtn = document.getElementById('cookiePreferences_3');\n    const closePreferencesBtn = document.getElementById('closePreferences_3');\n    const savePreferencesBtn = document.getElementById('savePreferences_3');\n    const analyticsCheck = document.getElementById('analyticsCheck_3');\n    const marketingCheck = document.getElementById('marketingCheck_3');\n    const cookieContent = cookieBanner.querySelector('.cookie-content');\n    const cookieIcon = cookieBanner.querySelector('.cookie-icon');\n    const cookieText = cookieBanner.querySelector('.cookie-text');\n    const cookieButtons = cookieBanner.querySelector('.cookie-buttons');\n\n    \/\/ Cookie fonksiyonlar\u0131\n    function setCookie(name, value, days) {\n        let expires = '';\n        if (days) {\n            const date = new Date();\n            date.setTime(date.getTime() + (days * 24 * 60 * 60 * 1000));\n            expires = '; expires=' + date.toUTCString();\n        }\n        document.cookie = name + '=' + (value || '') + expires + '; path=\/';\n    }\n    \n    function getCookie(name) {\n        const nameEQ = name + '=';\n        const ca = document.cookie.split(';');\n        for (let i = 0; i < ca.length; i++) {\n            let c = ca[i];\n            while (c.charAt(0) === ' ') c = c.substring(1, c.length);\n            if (c.indexOf(nameEQ) === 0) return c.substring(nameEQ.length, c.length);\n        }\n        return null;\n    }\n\n    \/\/ T\u00fcm \u00e7erezleri kabul et\n    function acceptAllCookies(event) {\n        \/\/ \u00c7erez tercihlerini kaydet\n        const preferences = {\n            analytics: true,\n            marketing: true\n        };\n        \n        setCookie('cookiePreferences_3', JSON.stringify(preferences), 365);\n        setCookie('cookieConsent_3', 'true', 365);\n        \n        \/\/ Cookie banner'\u0131 ikona d\u00f6n\u00fc\u015ft\u00fcr\n        cookieBanner.classList.add('icon-only');\n        \n        \/\/ Event bubbling'i durdur\n        event.stopPropagation();\n    }\n\n    \/\/ Tercihler panelini g\u00f6ster\n    function showPreferencesPanel() {\n        preferencesPanel.classList.add('active');\n    }\n\n    \/\/ Tercihler panelini gizle\n    function hidePreferencesPanel() {\n        preferencesPanel.classList.remove('active');\n    }\n\n    \/\/ Kullan\u0131c\u0131 tercihlerini kaydet\n    function savePreferences(event) {\n        const preferences = {\n            analytics: analyticsCheck.checked,\n            marketing: marketingCheck.checked\n        };\n        \n        setCookie('cookiePreferences_3', JSON.stringify(preferences), 365);\n        setCookie('cookieConsent_3', 'true', 365);\n        \n        hidePreferencesPanel();\n        cookieBanner.classList.add('icon-only');\n        \n        \/\/ Event bubbling'i durdur\n        if (event) event.stopPropagation();\n    }\n\n    \/\/ Kaydedilmi\u015f tercihleri y\u00fckle\n    function loadSavedPreferences() {\n        const savedPreferences = getCookie('cookiePreferences_3');\n        \n        if (savedPreferences) {\n            const preferences = JSON.parse(savedPreferences);\n            analyticsCheck.checked = preferences.analytics;\n            marketingCheck.checked = preferences.marketing;\n        }\n    }\n\n    \/\/ Cookie banner'\u0131 g\u00f6ster (varsay\u0131lan durumda veya ikonu g\u00f6ster)\n    function initCookieBanner() {\n        const hasConsent = getCookie('cookieConsent_3') === 'true';\n        \n        \/\/ Banner'\u0131 g\u00f6r\u00fcn\u00fcr yap\n        setTimeout(() => {\n            cookieBanner.classList.add('active');\n            \n            \/\/ E\u011fer daha \u00f6nce kabul edildiyse ikona d\u00f6n\u00fc\u015ft\u00fcr\n            if (hasConsent) {\n                cookieBanner.classList.add('icon-only');\n            }\n        }, 1000);\n    }\n\n    \/\/ \u0130kona t\u0131kland\u0131\u011f\u0131nda banner'\u0131 yeniden a\u00e7\n    cookieBanner.addEventListener('click', function(e) {\n        \/\/ E\u011fer zaten ikon modundaysa ve t\u0131klanan element kabul et butonu DE\u011e\u0130LSE\n        if (cookieBanner.classList.contains('icon-only') && \n            !e.target.closest('#acceptCookies_3')) {\n            \n            \/\/ Banner i\u00e7eri\u011fini \u00f6nceden gizle ve h\u0131zl\u0131 bir \u015fekilde banner'a ge\u00e7\n            cookieContent.style.opacity = '0';\n            \n            \/\/ CSS s\u0131n\u0131f\u0131n\u0131 kald\u0131r\n            cookieBanner.classList.remove('icon-only');\n            \n            \/\/ \u00c7ok k\u0131sa bir gecikme sonra i\u00e7eri\u011fi g\u00f6ster (ge\u00e7i\u015f animasyonundan sonra)\n            setTimeout(() => {\n                cookieContent.style.opacity = '1';\n                cookieContent.style.transition = 'opacity 0.3s ease';\n            }, 50);\n        }\n    });\n\n    \/\/ Event listeners\n    acceptCookiesBtn.addEventListener('click', acceptAllCookies);\n    cookiePreferencesBtn.addEventListener('click', showPreferencesPanel);\n    closePreferencesBtn.addEventListener('click', hidePreferencesPanel);\n    savePreferencesBtn.addEventListener('click', savePreferences);\n    \n    \/\/ Ba\u015flang\u0131\u00e7ta \u00e7erez tercihlerini y\u00fckle ve banner'\u0131 g\u00f6ster\n    loadSavedPreferences();\n    initCookieBanner();\n});\n<\/script> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211;HAAR \u2212ZAHN \u2212PLASTISCH \u2212MEDIZINISCH \u2212THERAPIEN DHI HAAR ZAHN PLASTISCH MEDIZINISCH THERAPIEN DHI Haartransplantation Die DHI (Direct Hair Implantation) Haartransplantation ist eine fortschrittliche Methode, die mit speziellen Choi-Stiften durchgef\u00fchrt wird. Bei dieser Technik werden die Haarwurzeln direkt in die Kopfhaut implantiert. Da keine Kanal\u00f6ffnung erforderlich ist, ist der Eingriff weniger traumatisch und die Heilung verl\u00e4uft schneller. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1360,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1396","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/drozdemirclinic.com\/de\/wp-json\/wp\/v2\/pages\/1396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drozdemirclinic.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/drozdemirclinic.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/drozdemirclinic.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/drozdemirclinic.com\/de\/wp-json\/wp\/v2\/comments?post=1396"}],"version-history":[{"count":0,"href":"https:\/\/drozdemirclinic.com\/de\/wp-json\/wp\/v2\/pages\/1396\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/drozdemirclinic.com\/de\/wp-json\/wp\/v2\/pages\/1360"}],"wp:attachment":[{"href":"https:\/\/drozdemirclinic.com\/de\/wp-json\/wp\/v2\/media?parent=1396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}